{"id":186,"date":"2014-01-07T09:51:42","date_gmt":"2014-01-07T08:51:42","guid":{"rendered":"http:\/\/www.flora-pharm.de\/blog\/?p=186"},"modified":"2022-11-17T08:19:41","modified_gmt":"2022-11-17T07:19:41","slug":"symbole-auf-verpackungen-z-b-fuer-haltbarkeitsdaten-kosmetischer-mittel","status":"publish","type":"post","link":"https:\/\/www.flora-pharm.de\/blog\/symbole-auf-verpackungen-z-b-fuer-haltbarkeitsdaten-kosmetischer-mittel\/","title":{"rendered":"Symbole auf Verpackungen, z.B. f\u00fcr Haltbarkeitsdaten kosmetischer Mittel"},"content":{"rendered":"<p>Immer wieder finden sich auf Verpackungen viele Symbole und Zeichen, die man nur zu gerne \u00fcbersieht oder auch einfach nicht kennt. Von besonderem Interesse sind die unscheinbaren Piktogramme, die auf Haltbarkeitsdaten oder Haltbarkeitszeitr\u00e4ume hinweisen. H\u00e4tte Sie sie erkannt?<\/p>\n<p>Die Sanduhr hat ausnahmsweise nichts mit Wartezeiten am Computer zu tun. Sie verweist auf das Mindesthaltbarkeitsdatum, das ist der Zeitpunkt, bis zu dem das Mittel bei sachgem\u00e4\u00dfer Aufbewahrung seine urspr\u00fcngliche Funktion erf\u00fcllt. Diese Angabe geh\u00f6rt auf jede Verpackung. Die Sanduhr kann auch durch die W\u00f6rter \u201eMindestens haltbar bis\u201c ersetzt werden. Ist das Mindesthaltbarkeitsdatum abh\u00e4ngig von bestimmten Aufbewahrungsbedingungen, so m\u00fcssen diese mit angegeben werden.<\/p>\n<p>F\u00fcr kosmetische Mittel mit einer Mindesthaltbarkeit von mehr als 30 Monaten ist die Angabe des Mindesthaltbarkeitsdatums nicht vorgeschrieben.<\/p>\n<p>Dort findet man dann bei wiederverschlie\u00dfbaren Verpackungen mit \u201everderblichem\u201c Inhalt das Tiegel-Symbol, das die Haltbarkeit nach der \u00d6ffnung anzeigt (auch PAO-Symbol f\u00fcr \u201eperiod after opening\u201c).<\/p>\n<p>Das Symbol mit dem ge\u00f6ffneten Tiegel wird mit der Angabe des Zeitraums in Monaten und\/oder Jahren erg\u00e4nzt.<\/p>\n<p>Es ist f\u00fcr die Wirksamkeit und Sicherheit eines Mittels wichtig, die Grenzen der Haltbarkeit zu kennen und zu beachten.<\/p>\n<p>\u00dcbrigens ist nunmehr generell eine neue Kosmetikverordnung in Kraft. Eine der ma\u00dfgeblichsten \u00c4nderungen betrifft hier die Sprache der Deklaration und der Herstellerangaben (nicht der Inhaltstoffe, diese werden <span style=\"text-decoration: underline;\">INCI<\/span> deklariert), da es dadurch vorgeschrieben ist, dass diese in der Landessprache des Landes, wo sich das Kosmetikum in Verkehr befindet, zu erfolgen hat. Wundern Sie sich also nicht, wenn einige Pr\u00e4parate so nicht mehr erh\u00e4ltlich sind oder sich das Packungsdesign grundlegend ge\u00e4ndert hat.<\/p>\n<p>Wenn Ihnen Symbole fremd oder Sie unsicher sind, k\u00f6nnen Sie uns immer gerne fragen.<\/p>\n<p><b>Weitere Informationen:<\/b><\/p>\n<ul>\n<li><a title=\"Beitragsquelle\" href=\"http:\/\/www.bvl.bund.de\/DE\/03_Bedarfsgegenstaende\/03_AntragstellerUnternehmen\/02_Kosmetik\/05_Kennzeichnung\/01_Haltbarkeitsdaten\/bgs_fuerAntragsteller_kosmetik_mhd_node.html\" rel=\"nofollow\">Quelle<\/a><\/li>\n<li>Mehr \u00fcber <a title=\"INCI\" href=\"http:\/\/de.wikipedia.org\/wiki\/Internationale_Nomenklatur_f%C3%BCr_kosmetische_Inhaltsstoffe\" rel=\"nofollow\">INCI<\/a> (<i>International Nomenclature of Cosmetic Ingredients<\/i>)<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Immer wieder finden sich auf Verpackungen viele Symbole und Zeichen, die man nur zu gerne \u00fcbersieht oder auch einfach nicht kennt. Von besonderem Interesse sind die unscheinbaren Piktogramme, die auf Haltbarkeitsdaten oder Haltbarkeitszeitr\u00e4ume hinweisen. H\u00e4tte Sie sie erkannt? Die Sanduhr hat ausnahmsweise nichts mit Wartezeiten am Computer zu tun. Sie verweist auf das Mindesthaltbarkeitsdatum, das [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":187,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[102,99,101,100],"class_list":["post-186","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenswert","tag-haltbarkeit","tag-kosmetik","tag-symbole","tag-verpackungen","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_featured_media_url":"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2014\/01\/MHD-PAO-auf-Verpackungen-kosmetischer-Mittel.jpg","jetpack-related-posts":[{"id":7359,"url":"https:\/\/www.flora-pharm.de\/blog\/teller-statt-tonne\/","url_meta":{"origin":186,"position":0},"title":"Teller statt Tonne","author":"Flora Team","date":"1. M\u00e4rz 2021","format":false,"excerpt":"Welke Salatk\u00f6pfe, schrumpelige \u00c4pfel, altbackene Brote, Mahlzeitenreste und sogar unge\u00f6ffnete Milchpackungen und Joghurts\u2026 Jedes Jahr landen allein in Privathaushalten rund sechs Millionen Tonnen Lebensmittel im M\u00fcll, das macht auf den Durchschnittsdeutschen runtergerechnet rund 75 Kilogramm Lebensmittel. Anders ausgedr\u00fcckt: Zwei vollgepackte Einkaufswagen mit Essen wirft jeder Bundesb\u00fcrger weg \u2013 im Wert\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Teller statt Tonne - Nachhaltig und bewusst einkaufen","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/01\/teller-statt-tonne.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/01\/teller-statt-tonne.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/01\/teller-statt-tonne.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/01\/teller-statt-tonne.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2797,"url":"https:\/\/www.flora-pharm.de\/blog\/alte-sonnencreme-wegwerfen\/","url_meta":{"origin":186,"position":1},"title":"Alte Sonnencreme wegwerfen?","author":"Flora Team","date":"22. Juli 2015","format":false,"excerpt":"Sonnencreme aus dem vergangenen Jahr \u2013 wegwerfen oder noch mal benutzen? Wer sich diese Frage stellt, findet in dem EU-weit einheitlichem PAO-Symbol (period after opening) die Antwort. Dieses zeigt einen offenen Cremetopf, gefolgt von einem Zeitraum, der die Haltbarkeit nach dem \u00d6ffnen angibt. Dies gilt aber nur bei richtiger Lagerung\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":243,"url":"https:\/\/www.flora-pharm.de\/blog\/verpackungssymbole-beipackzettel-und-schwangerschaft\/","url_meta":{"origin":186,"position":2},"title":"Verpackungssymbole, Beipackzettel und Schwangerschaft","author":"Flora Team","date":"5. M\u00e4rz 2014","format":false,"excerpt":"Wegen der vielen Nachfragen zu unserem Artikel \u201eSymbole auf Verpackungen, z.B. f\u00fcr Haltbarkeitsdaten\u201c, m\u00f6chten wir noch zwei weitere Symbole vorstellen, die wir zudem dazu nutzen m\u00f6chten, auf wichtige Verhaltensregeln bei der Einnahme von Medikamenten hinzuweisen\u2026 \u00a0 Das Symbol mit dem Lesefinger im Heft (links im Bild) wird im Kosmetikbereich verwendet\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2014\/03\/Symbole-Schwanger-Beipackzettel.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2014\/03\/Symbole-Schwanger-Beipackzettel.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2014\/03\/Symbole-Schwanger-Beipackzettel.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2014\/03\/Symbole-Schwanger-Beipackzettel.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3917,"url":"https:\/\/www.flora-pharm.de\/blog\/lebensmittelzusatz-e171-titandioxid-moeglicherweise-krebserregend\/","url_meta":{"origin":186,"position":3},"title":"Lebensmittelzusatz E171 (Titandioxid) m\u00f6glicherweise krebserregend","author":"Flora Team","date":"3. M\u00e4rz 2017","format":false,"excerpt":"In nahezu allen Produkten finden sich diese \u201eE-Stoffe\u201c, die Lebensmittelzus\u00e4tze, die in einigen F\u00e4llen lediglich dazu dienen, ein Produkt besser verkaufbar zu machen. Lebensmittelzusatzstoffe sollen in Lebensmitteln (aber auch Kosmetikprodukten) chemische, physikalische oder auch physiologische Effekte bewirken. Sie beeinflussen Struktur, Geschmack, Geruch, Farbe und\/oder Haltbarkeit und k\u00f6nnen sowohl synthetische Stoffe\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2017\/03\/e171.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2017\/03\/e171.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2017\/03\/e171.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2017\/03\/e171.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8860,"url":"https:\/\/www.flora-pharm.de\/blog\/deo\/","url_meta":{"origin":186,"position":4},"title":"Deo","author":"Flora Team","date":"27. September 2023","format":false,"excerpt":"Jeder zweite Deutsche benutzt es t\u00e4glich mindestens einmal: Deo! Die Auswahl ist so gro\u00df wie die Liste bedenklicher Inhaltsstoffe. Welches ist das richtige f\u00fcr Sie?","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Deodorant","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/08\/deo-dorant.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/08\/deo-dorant.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/08\/deo-dorant.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/08\/deo-dorant.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/08\/deo-dorant.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":2578,"url":"https:\/\/www.flora-pharm.de\/blog\/karneval-2015-steht-vor-der-tuer-pruefen-sie-ihre-schminke\/","url_meta":{"origin":186,"position":5},"title":"Karneval 2015 steht vor der T\u00fcr, pr\u00fcfen Sie Ihre Schminke!","author":"Flora Team","date":"11. Februar 2015","format":false,"excerpt":"Egal ob Helau oder Alaaf: kommen Sie gut durch die n\u00e4rrische Zeit! Zu einem stilechten Kost\u00fcm geh\u00f6rt nat\u00fcrlich auch das passend geschminkte Gesicht \u2013 leider oft mit b\u00f6sen Folgen in Form von Pickeln, Pusteln oder Juckreiz. Testen Sie daher besser rechtzeitig vor den \u201etollen Tagen\u201c, ob Ihre Haut und insbesondere\u2026","rel":"","context":"In &quot;Kalenderlexikon&quot;","block_context":{"text":"Kalenderlexikon","link":"https:\/\/www.flora-pharm.de\/blog\/category\/kalenderlexikon\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/02\/karneval-schminke.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/02\/karneval-schminke.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/02\/karneval-schminke.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/02\/karneval-schminke.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":3,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/186\/revisions"}],"predecessor-version":[{"id":8503,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/186\/revisions\/8503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media\/187"}],"wp:attachment":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media?parent=186"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/categories?post=186"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/tags?post=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}