{"id":4870,"date":"2018-03-12T11:58:39","date_gmt":"2018-03-12T10:58:39","guid":{"rendered":"http:\/\/www.flora-pharm.de\/blog\/?p=4870"},"modified":"2018-03-12T11:58:39","modified_gmt":"2018-03-12T10:58:39","slug":"baby-vertrauen-instinkt-hebamme","status":"publish","type":"post","link":"https:\/\/www.flora-pharm.de\/blog\/baby-vertrauen-instinkt-hebamme\/","title":{"rendered":"Babys vertrauen ihrem Instinkt"},"content":{"rendered":"<p>Die Geburt des ersten Kindes ist wie ein Sprung ins kalte Wasser. Pl\u00f6tzlich Mutter \u2013 verantwortlich f\u00fcr ein winziges B\u00fcndel Leben. Jede Situation mit Baby ist eine komplett neue Lebenserfahrung. Wie gut, dass es Hebammen wie Susanne Steppat gibt! <strong>Ein Interview.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Die Betreuung einer Hebamme endet nicht mit der Geburt, ganz im Gegenteil. Welche Ver\u00e4nderungen pr\u00e4gen die ersten Tage?<\/em><\/strong><br \/>\nIn medizinischer Hinsicht achte ich bei der Mutter auf die Br\u00fcste sowie R\u00fcckbildungsvorg\u00e4nge, Verletzungen und N\u00e4hte, haupts\u00e4chlich im Intimbereich. Beim Baby beobachte ich insbesondere s\u00e4mtliche Vitalfunktionen, die Haut und die Gewichtszunahme. Ein Schwerpunkt liegt auf der Unterst\u00fctzung der Mutter beim Stillen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Haben junge Eltern anfangs Ber\u00fchrungs\u00e4ngste?<\/em><\/strong><br \/>\nNat\u00fcrlich, sie tragen Verantwortung f\u00fcr das Baby und sind mit v\u00f6llig neuen Aufgaben betraut. Viele wagen sich zun\u00e4chst nicht so recht an den Nabelbereich, die Augen und den Intimbereich des Kleinen heran. Davor nehme ich ihnen die Angst.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00bbEltern brauchen die acht Wochen Hebammenbetreuung nach der Geburt, um sich in der neuen Situation zu finden.\u00ab<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong><em>M\u00fcssen sich Mama und Baby erst kennenlernen?<\/em><\/strong><br \/>\nJedes Mutter-Kind-Gespann ist ein individuelles Team. Beide lernen, sich aufeinander einzulassen und die Sprache des anderen zu lesen. Die Verbundenheit und ein instinktiver Umgang miteinander entwickeln sich. F\u00fcr viele M\u00fctter gibt es irgendwann kein Ich mehr, sondern nur noch ein Wir.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Pl\u00f6tzlich Verantwortung f\u00fcr ein hilfloses Neugeborenes zu tragen, macht auch Angst&#8230;<\/em><\/strong><br \/>\nJa, die Zeit nach der Geburt brauchen die Eltern f\u00fcr ihren pers\u00f6nlichen psychosozialen Entwicklungsprozess. Nicht umsonst spricht man vom \u00bbWochenbett\u00ab, also mehreren Wochen Gew\u00f6hnungsphase. Es braucht Zeit, bis Eltern ihre Unsicherheit ablegen und ihre neue Rolle verinnerlicht haben.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Sollten M\u00fctter mehr Selbstvertrauen haben?<\/em><\/strong><br \/>\nEs gilt, ein grundlegendes Vertrauen in sich als f\u00e4hige Mutter zu entwickeln. Manchmal m\u00fcssen Frauen (wieder) lernen, auf ihren Instinkt zu h\u00f6ren und danach zu handeln. Lernen, Bed\u00fcrfnisse und Erfahrungen zu erkennen und einzuordnen. In der Regel ist es gut so, wie die Mutter handelt. Ich versuche, den von mir betreuten M\u00fcttern auf den Weg zu geben: Wenn du gl\u00fccklich bist, ist auch das Baby gl\u00fccklich.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00bbM\u00fctter haben \u00e4hnliche Fragen, aber es gibt unterschiedliche L\u00f6sungen.\u00ab<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p><strong><em>Ein Problem vieler M\u00fctter: der neue Tagesablauf.<\/em><\/strong><br \/>\nIch rate werdenden Eltern, vor der Geburt zu kl\u00e4ren, wie die erste Zeit mit Baby organisiert werden kann. Das Stillen oder F\u00fcttern und die Betreuung des Babys kosten viel Zeit und Kraft. Das Ziel ist ein Arrangement zwischen eigenen Bed\u00fcrfnissen und der Verantwortung f\u00fcr das Kind, mit dem alle zufrieden sind.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Was ist mit den gut gemeinten Ratschl\u00e4gen?<\/em><\/strong><br \/>\nDie k\u00f6nnen ein Problem werden, wenn Eltern sich zu sehr beeinflussen lassen. Frischgebackene M\u00fctter sind da sehr empfindsam und reagieren h\u00e4ufig mit einem sogenannten Milchstau. Jedes Mutter-Kind-Team hat eigene Bed\u00fcrfnisse und Gewohnheiten. Vergleiche und Leistungsdruck sind nicht angebracht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><em>Warum legt der Deutsche Hebammenverband besonderen Wert auf eine enge Mutter-Kind-Bindung?<\/em><\/strong><br \/>\nDas Bonding, also der intensive Hautkontakt von Mutter und Kind, bewirkt eine verst\u00e4rkte Aussch\u00fcttung des Hormons Oxytocin. Das st\u00e4rkt die Bindung und bildet die Basis f\u00fcr eine liebevolle Beziehung. Das Haut-an-Haut-Liegen passt wunderbar zum Entwicklungsstand des Babys, das sich stark an Ger\u00fcchen orientiert.<\/p>\n<p>Die Situation in Deutschland ist angespannt, einige Schwangere suchen lange nach \u00bbihrer\u00ab Hebamme. Zurzeit herrscht ein Ungleichgewicht von Angebot und Nachfrage. Einige Hebammen arbeiten nicht in Vollzeit oder nur in bestimmten Bereichen, daher kommt es manchmal bei der Wochenbettbetreuung zu Engp\u00e4ssen. Und der Anspruch an uns w\u00e4chst. Ich rate Schwangeren, sich ab dem dritten Monat auf die Suche zu machen und eine Hebamme bereits in die Vorsorge einzubinden. Kliniken und andere M\u00fctter k\u00f6nnen Hebammen empfehlen. Manche Schwangere hat Sorge, dass eine Hebamme nicht zu ihr \u00bbpasst\u00ab. Das ist unbegr\u00fcndet denn Hebammen arbeiten professionell.<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><em>\u00bbHebamme ist ein Traumberuf: selbstbestimmt, erf\u00fcllend und voller Erfolgserlebnisse.\u00ab<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Bei 730.000 Geburten im Jahr haben Hebammen viele Fragen zu beantworten.<\/p>\n<h2>Die Hebamme: Unverzichtbar in den ersten Tagen<\/h2>\n<p>In den acht Wochen nach der Geburt unterst\u00fctzt die Hebamme die Eltern beim richtigen Umgang mit dem Neugeborenen. Sie hat ein Auge auf R\u00fcckbildung und Wundheilung bei der Mutter sowie die Entwicklung des Kindes und die Mutter-Kind-Beziehung. Bei Still- und Ern\u00e4hrungsproblemen ber\u00e4t sie dar\u00fcber hinaus. Viele Hebammen bieten Kurse in R\u00fcckbildungs- und Beckenbodengymnastik, nat\u00fcrlicher Familienplanung und Babymassage an. Jede Frau kann Hebammenhilfe in Anspruch nehmen. Viele Leistungen werden bei gesetzlich versicherten Frauen von deren Krankenkasse bezahlt, etwa ein Geburtsvorbereitungskurs, die Betreuung im Wochenbett und ein R\u00fcckbildungskurs. \u00dcbrigens d\u00fcrfen Hebammen Medikamente direkt an ihre Patientinnen abgeben.<br \/>\nMehr wissen? <a href=\"http:\/\/www.hebammenverband.de\/\" rel=\"nofollow\" target=\"_blank\">www.hebammenverband.de<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>Auch hier im Blog finden Sie weitere Artikel zu den Themen <a href=\"https:\/\/www.flora-pharm.de\/blog\/tag\/kleinkind\/\">Kleinkind<\/a>, <a href=\"https:\/\/www.flora-pharm.de\/blog\/tag\/schwangerschaft\/\">Schwangerschaft<\/a> und <a href=\"https:\/\/www.flora-pharm.de\/blog\/tag\/stillzeit\/\">Stillzeit<\/a>. Zus\u00e4tzlich k\u00f6nnen Sie uns gern ansprechen und befragen, Beratung wird bei uns gro\u00dfgeschrieben.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4857\" aria-describedby=\"caption-attachment-4857\" style=\"width: 242px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018.jpg\"><img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"4857\" data-permalink=\"https:\/\/www.flora-pharm.de\/blog\/baby-vertrauen-instinkt-hebamme\/fug-10\/\" data-orig-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018.jpg\" data-orig-size=\"450,557\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;FuG&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"FuG\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Text mit freundlicher Genehmigung der S&amp;#038;D Verlag GmbH. Die komplette &amp;#8222;nat\u00fcrlich Frau&amp;#8220; bekommen Sie auch bei uns in der Apotheke als monatliches Special in der &amp;#8222;Naturheilkunde &amp;#038; Gesundheit&amp;#8220;.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018.jpg\" src=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018-242x300.jpg\" alt=\"\" width=\"242\" height=\"300\" class=\"size-medium wp-image-4857\" srcset=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018-242x300.jpg 242w, https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/natuerlich-frau-cover-03-2018.jpg 450w\" sizes=\"auto, (max-width: 242px) 100vw, 242px\" \/><\/a><figcaption id=\"caption-attachment-4857\" class=\"wp-caption-text\">Text mit freundlicher Genehmigung der S&#038;D Verlag GmbH. Die komplette &#8222;nat\u00fcrlich Frau&#8220; bekommen Sie auch bei uns in der Apotheke als monatliches Special in der &#8222;Naturheilkunde &#038; Gesundheit&#8220;.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Die Geburt des ersten Kindes ist wie ein Sprung ins kalte Wasser. Pl\u00f6tzlich Mutter \u2013 verantwortlich f\u00fcr ein winziges B\u00fcndel Leben. Jede Situation mit Baby ist eine komplett neue Lebenserfahrung. Wie gut, dass es Hebammen wie Susanne Steppat gibt! Ein Interview. &nbsp; Die Betreuung einer Hebamme endet nicht mit der Geburt, ganz im Gegenteil. Welche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[574,64],"class_list":["post-4870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenswert","tag-hebamme","tag-kleinkind","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_featured_media_url":"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/babys-vertrauen-instinkt.jpg","jetpack-related-posts":[{"id":4898,"url":"https:\/\/www.flora-pharm.de\/blog\/pflegestufe-zwei-gutes-fuer-mama-baby\/","url_meta":{"origin":4870,"position":0},"title":"Pflegestufe Zwei &#8211; Gutes f\u00fcr Mama &#038; Baby","author":"Flora Team","date":"26. M\u00e4rz 2018","format":false,"excerpt":"\u201eF\u00fcr Mutter und Baby beginnt nach der Geburt eine spannende Zeit\u201c, sagt Cathrin H\u00e4usser, pharmazeutisch-technische Assistentin in Weissach. \u201eBesonders beim ersten Kind ist alles neu. Viele M\u00fctter sind unsicher, welche Pflegeprodukte und Arzneimittel sie verwenden k\u00f6nnen und d\u00fcrfen.\u201c PS: Lesen Sie auch unseren Artikel Nat\u00fcrliche Babypflege. Alles f\u00fcr Mutter und\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/pflegestufe-zwei.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/pflegestufe-zwei.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/pflegestufe-zwei.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/03\/pflegestufe-zwei.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3420,"url":"https:\/\/www.flora-pharm.de\/blog\/immunsystem-es-beginnt-in-mutters-schwangerschaft\/","url_meta":{"origin":4870,"position":1},"title":"Immunsystem, es beginnt in Mutters Schwangerschaft","author":"Flora Team","date":"16. September 2016","format":false,"excerpt":"Nach \u00fcberraschend vielen R\u00fcckmeldungen zu unserem Artikel \u201eNat\u00fcrliche Babypflege\u201c m\u00f6chten wir zum Thema Baby noch einen Beitrag nachlegen und beleuchten hier nun das Neonatale Immunsystem. Unser Immunsystem hat einen ganz einfachen Sinn, es soll ungef\u00e4hrliche Stoffe in den K\u00f6rper lassen, (potentiell) gef\u00e4hrliche (z.B. Viren, Bakterien, Allergene) dagegen ausfiltern und den\u2026","rel":"","context":"In &quot;Flora Apotheke&quot;","block_context":{"text":"Flora Apotheke","link":"https:\/\/www.flora-pharm.de\/blog\/category\/flora-apotheke\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/Neonatales%20Immunsystem.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/Neonatales%20Immunsystem.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/Neonatales%20Immunsystem.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/Neonatales%20Immunsystem.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":3416,"url":"https:\/\/www.flora-pharm.de\/blog\/natuerliche-babypflege\/","url_meta":{"origin":4870,"position":2},"title":"Nat\u00fcrliche Babypflege","author":"Flora Team","date":"12. September 2016","format":false,"excerpt":"Zartes muss sanft gepflegt werden! Zur Geburt eines Babys bekommen frisch gebackene Eltern eine Menge Empfehlungen und Tipps. Viele neue Aufgaben wollen bew\u00e4ltigt werden, darunter die S\u00e4uglingspflege. Dabei ist eine nat\u00fcrliche Babypflege recht einfach. Es gilt die Devise: Weniger ist mehr! Lassen Sie sich nicht verunsichern. Vieles, wie Windeln wechseln,\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/babypflege.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/babypflege.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/babypflege.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2016\/09\/babypflege.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7057,"url":"https:\/\/www.flora-pharm.de\/blog\/schwangerschaft-gesunder-start\/","url_meta":{"origin":4870,"position":3},"title":"Schwangerschaft &#8211; Gesunder Start","author":"Flora Team","date":"13. Juli 2020","format":false,"excerpt":"Schwanger sein bedeutet Verantwortung f\u00fcr ein zweites Leben. Saskia Fechte erkl\u00e4rt, worauf es jetzt ankommt? Finden Sie auch hier im Blog weitere Artikel zum Thema Schwangerschaft. Was Sie essen und trinken. Ob Sie entspannt oder gestresst sind. All das bekommt Ihr Baby mit. Grund genug, sich Gedanken \u00fcber einige Gewohnheiten\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Schwangerschaft - Gesunder Start","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/schwangerschaft-gesunder-start.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/schwangerschaft-gesunder-start.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/schwangerschaft-gesunder-start.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/schwangerschaft-gesunder-start.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":7863,"url":"https:\/\/www.flora-pharm.de\/blog\/baby-durch-die-blume\/","url_meta":{"origin":4870,"position":4},"title":"Baby durch die Blume","author":"Flora Team","date":"4. Oktober 2021","format":false,"excerpt":"Phytotherapie kann die Fruchtbarkeit f\u00f6rdern: Schon seit Jahrhunderten machen sich Frauen mit Kinderwunsch die Kraft der Heilpflanzen zunutze.","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Baby durch die Blume","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/09\/Baby-durch-die-Blume.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/09\/Baby-durch-die-Blume.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/09\/Baby-durch-die-Blume.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2021\/09\/Baby-durch-die-Blume.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":2974,"url":"https:\/\/www.flora-pharm.de\/blog\/frauenkraeuter-fuer-jede-lebensphase\/","url_meta":{"origin":4870,"position":5},"title":"Frauenkr\u00e4uter f\u00fcr jede Lebensphase","author":"Flora Team","date":"13. November 2015","format":false,"excerpt":"Von der ersten Regelblutung bis zu den Wechseljahren helfen Kr\u00e4uter und Heilpflanzen auf nat\u00fcrliche Weise. Kinderwunsch Bei unerf\u00fclltem Kinderwunsch k\u00f6nnen Pflanzenstoffe mit Hormonwirkung hilfreich sein. Die Naturheilkunde nutzt Pr\u00e4parate aus Rotklee, Traubensilberkerze, Sibirischer Rhabarberwurzel und M\u00f6nchspfeffer. Diese traditionellen Frauenkr\u00e4uter haben Einfluss auf einen stabilen Zyklus und damit auch auf die\u2026","rel":"","context":"In &quot;Heilpflanzen \/ Arzneipflanzen&quot;","block_context":{"text":"Heilpflanzen \/ Arzneipflanzen","link":"https:\/\/www.flora-pharm.de\/blog\/category\/heilpflanzen-arzneipflanzen\/"},"img":{"alt_text":"Mit freundlicher Genehmigung der S & D Verlag GmbH. Das komplette Heft bekommen Sie auch bei uns in der Apotheke.","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/11\/cover-NuG-11-2015-225x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/4870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/comments?post=4870"}],"version-history":[{"count":2,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/4870\/revisions"}],"predecessor-version":[{"id":4872,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/4870\/revisions\/4872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media\/4855"}],"wp:attachment":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media?parent=4870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/categories?post=4870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/tags?post=4870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}