{"id":5558,"date":"2018-12-19T10:03:09","date_gmt":"2018-12-19T09:03:09","guid":{"rendered":"http:\/\/www.flora-pharm.de\/blog\/?p=5558"},"modified":"2018-12-19T10:03:13","modified_gmt":"2018-12-19T09:03:13","slug":"eichhoernchen-fuettern","status":"publish","type":"post","link":"https:\/\/www.flora-pharm.de\/blog\/eichhoernchen-fuettern\/","title":{"rendered":"Eichh\u00f6rnchen f\u00fcttern?"},"content":{"rendered":"<p><strong>Die Antwort vorweg: Kann, muss aber nicht.<\/strong><br>\nDie extreme Trockenheit des Sommers und der ebenfalls sehr regenarme Herbst haben den meisten B\u00fcschen und B\u00e4umen weniger zugesetzt, als zu vermuten w\u00e4re.<br>\nM\u00f6chten Sie den Eichh\u00f6rnchen in Ihrer Umgebung mit einer zus\u00e4tzlichen F\u00fctterung trotzdem etwas Gutes tun, m\u00fcssen Sie zum Wohl der Tiere auf einige Dinge achten.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ein Artikel von Karsten Kulms.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Das vergangene Jahr war zwar kein ausgesprochen ertragreiches Nussjahr. Daf\u00fcr aber f\u00fcr viele B\u00fcsche und B\u00e4ume ein sogenanntes \u201eMastjahr\u201c. Das bedeutet, dass im Fr\u00fchling und Fr\u00fchsommer mehrere Baumarten gleichzeitig und besonders reichhaltig gebl\u00fcht haben. Dadurch haben die flei\u00dfigen Eichh\u00f6rnchen im Herbst vor allem Eicheln und Bucheckern in H\u00fclle und F\u00fclle finden und ihren Vorr\u00e4ten einverleiben k\u00f6nnen. Nach Angaben von Experten der gro\u00dfen Umweltschutzverb\u00e4nde kann von einem ernsten Futtermangel f\u00fcr die pinselohrigen Waldbewohner im Winter daher keine Rede sein.<\/p>\n<p>&nbsp;<\/p>\n<h3>F\u00fcttern und beobachten<\/h3>\n<p>Dass es genug Futter f\u00fcr sie gibt, schlie\u00dft nat\u00fcrlich nicht aus, dass sich Eichh\u00f6rnchen \u00fcber einen zus\u00e4tzlichen Happen sehr freuen. M\u00f6chten Sie die Tiere auf der Futtersuche gerne beobachten, k\u00f6nnen Sie ihnen in Ihrem Garten Futter bereitstellen. Am meisten freuen sie sich \u00fcber Hasel- und Waln\u00fcsse, S\u00e4mereien und Sonnenblumenkerne. Eine reine Erdnuss-Di\u00e4t dagegen schadet mehr, als sie n\u00fctzt. F\u00fcr die Beobachtung von Eichh\u00f6rnchen m\u00fcssen Sie in dieser Jahreszeit viel Zeit mitbringen. Denn sie halten zwar keinen durchg\u00e4ngigen Winterschlaf, aber eine Winterruhe, bei der sie ihr Winterquartier, den sogenannten \u201eKobel\u201c, meist mehrere Tage lang nicht verlassen. Begegnungen mit einem Eichh\u00f6rnchen sind im Winter daher eher selten.<\/p>\n<p>&nbsp;<\/p>\n<h3>Spezielle Futterk\u00e4sten<\/h3>\n<p>Im Fachhandel gibt es speziell gearbeitete Futterk\u00e4sten, die auf den Besuch von Eichh\u00f6rnchen ausgerichtet sind. Sie \u00e4hneln in ihrer Form einem Vogelh\u00e4uschen, haben aber eine Front aus durchsichtigem Plexiglas und ein nach oben zu \u00f6ffnendes Dach. Durch die Plexiglasscheibe erkennen die Tiere, dass sich in dem Kasten Futter befindet, an dem sie sich durch \u00d6ffnen des Deckels problemlos bedienen k\u00f6nnen. Die Tiere lernen sehr schnell, den Deckel zu \u00f6ffnen und sich eine Nuss herauszuholen.<\/p>\n<p>&nbsp;<\/p>\n<h3>Bitte nicht sammeln<\/h3>\n<p>Natursch\u00fctzer raten dazu, den Eichh\u00f6rnchen am eigenen Futterh\u00e4uschen nur gekauftes Futter aus dem Fachhandel anzubieten. Denn im Wald N\u00fcsse, Eicheln und Bucheckern f\u00fcr sie zu sammeln, schadet anderen Waldbewohnern wie Wildschweinen oder V\u00f6geln. Denn sie legen keine Vorr\u00e4te an, sondern sind auf das Futter angewiesen, das sie jetzt finden.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ungebetene G\u00e4ste<\/h3>\n<p>Im Winter gezielt nur eine einzelne Tierart zu f\u00fcttern ist nahezu unm\u00f6glich. Denn das aufgestellte Eichh\u00f6rnchenfutter schmeckt auch weniger beliebten Tierarten wie M\u00e4usen, Ratten oder Waschb\u00e4ren. Auch aus diesem Grund ist es wichtig, am Futterplatz auf Hygiene zu achten und das Futter t\u00e4glich auf Verunreinigungen zu kontrollieren und gegebenenfalls auszutauschen. Bedenken Sie zudem, dass das F\u00fcttern von Wildtieren an einem gemeinsamen Ort immer auch die Gefahr der \u00dcbertragung von Krankheiten birgt.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" data-attachment-id=\"5486\" data-permalink=\"https:\/\/www.flora-pharm.de\/blog\/linke-seite-58\/\" data-orig-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/unsere-besten-freunde-cover-12-2018.jpg\" data-orig-size=\"450,600\" data-comments-opened=\"1\" data-image-title=\"Unsere besten Freunde\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Text mit freundlicher Genehmigung der S &amp;#038; D Verlag GmbH. Das komplette &amp;#8222;Unsere besten Freunde&amp;#8220; Heft bekommen Sie auch bei uns in der Apotheke.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/unsere-besten-freunde-cover-12-2018.jpg\" src=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/unsere-besten-freunde-cover-12-2018-225x300.jpg\" alt=\"Unsere besten Freunde Cover\" class=\"wp-image-5486\" srcset=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/unsere-besten-freunde-cover-12-2018-225x300.jpg 225w, https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/unsere-besten-freunde-cover-12-2018.jpg 450w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption>Text mit freundlicher Genehmigung der S &amp; D Verlag GmbH. Das komplette &#8222;Unsere besten Freunde&#8220; Heft bekommen Sie auch bei uns in der Apotheke.<\/figcaption><\/figure><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Die Antwort vorweg: Kann, muss aber nicht. Die extreme Trockenheit des Sommers und der ebenfalls sehr regenarme Herbst haben den meisten B\u00fcschen und B\u00e4umen weniger zugesetzt, als zu vermuten w\u00e4re. M\u00f6chten Sie den Eichh\u00f6rnchen in Ihrer Umgebung mit einer zus\u00e4tzlichen F\u00fctterung trotzdem etwas Gutes tun, m\u00fcssen Sie zum Wohl der Tiere auf einige Dinge achten. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5479,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[33,8],"tags":[56],"class_list":["post-5558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-haustiere","category-wissenswert","tag-futter","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_featured_media_url":"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/11\/Eichhoernchen-fuettern.jpg","jetpack-related-posts":[{"id":5958,"url":"https:\/\/www.flora-pharm.de\/blog\/vogelfuetterung-im-winter-artgerecht-schmeckts-am-besten\/","url_meta":{"origin":5558,"position":0},"title":"Vogelf\u00fctterung im Winter &#8211; Artgerecht schmeckt\u2019s am besten","author":"Flora Team","date":"13. Januar 2021","format":false,"excerpt":"Wird das Futterangebot f\u00fcr unsere heimischen Winterv\u00f6gel knapp, sch\u00e4tzen sie es sehr, wenn ihnen bei der Futtersuche ein wenig unter die Fl\u00fcgel gegriffen wird. Dabei hat jede Vogelart ihre Vorlieben. Damit sich V\u00f6gel wie Meisen, Finken, Rotkehlchen und andere hungrige Winterg\u00e4ste an einer Futterstelle ungest\u00f6rt satt fressen k\u00f6nnen, gibt der\u2026","rel":"","context":"In &quot;Haustiere&quot;","block_context":{"text":"Haustiere","link":"https:\/\/www.flora-pharm.de\/blog\/category\/haustiere\/"},"img":{"alt_text":"V\u00f6gel f\u00fcttern - aber artgerecht","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/02\/voegel-fuettern-artgerecht.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/02\/voegel-fuettern-artgerecht.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/02\/voegel-fuettern-artgerecht.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/02\/voegel-fuettern-artgerecht.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":9337,"url":"https:\/\/www.flora-pharm.de\/blog\/wir-bleiben-hier\/","url_meta":{"origin":5558,"position":1},"title":"Wir bleiben hier","author":"Flora Team","date":"11. Oktober 2024","format":false,"excerpt":"Viele heimische Vogelarten verweilen hier trotz niedriger Temperaturen und knappem Nahrungsangebot, w\u00e4hrend andere den warmen S\u00fcden suchen.","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Einige Wildv\u00f6gel \u00fcberwintern hier. Wie k\u00f6nnen wir Sie unterst\u00fctzen?","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/10\/wir-bleiben-hier-wildvoegel-ueberwintern.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/10\/wir-bleiben-hier-wildvoegel-ueberwintern.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/10\/wir-bleiben-hier-wildvoegel-ueberwintern.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/10\/wir-bleiben-hier-wildvoegel-ueberwintern.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/10\/wir-bleiben-hier-wildvoegel-ueberwintern.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8932,"url":"https:\/\/www.flora-pharm.de\/blog\/herbstlaub\/","url_meta":{"origin":5558,"position":2},"title":"Herbstlaub","author":"Flora Team","date":"14. November 2023","format":false,"excerpt":"Herbstlaub: Sie leuchten in den sch\u00f6nsten Farben und rascheln so herrlich unter den F\u00fc\u00dfen \u2013 bunte Bl\u00e4tter. Und sie sind n\u00fctzlich!","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Buntes, n\u00fctzliches Herbstlaub","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/10\/herbstlaub.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/10\/herbstlaub.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/10\/herbstlaub.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/10\/herbstlaub.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2023\/10\/herbstlaub.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":5349,"url":"https:\/\/www.flora-pharm.de\/blog\/floehe-herbstzeit-ist-parasitenzeit\/","url_meta":{"origin":5558,"position":3},"title":"Fl\u00f6he &#8211; Herbstzeit ist Parasitenzeit","author":"Flora Team","date":"11. Oktober 2018","format":false,"excerpt":"So sch\u00fctzen Sie Ihren Vierbeiner vor Flohbefall \u00dcber die kleinen Parasiten kursieren viele Irrt\u00fcmer. Diese 5 Mythen haben in der Haltung von Hunden und Katzen nichts zu suchen. Wir verraten, wie Ihr Vierbeiner Ruhe vor ungebetenen G\u00e4sten hat. PS: Lesen Sie auch unseren Artikel \u00fcber Tierparasiten. \u00a0 Ein Artikel von\u2026","rel":"","context":"In &quot;Haustiere&quot;","block_context":{"text":"Haustiere","link":"https:\/\/www.flora-pharm.de\/blog\/category\/haustiere\/"},"img":{"alt_text":"Fl\u00f6he, Parasitenzeit Herbst","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/10\/herbst-parasiten-floh.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/10\/herbst-parasiten-floh.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/10\/herbst-parasiten-floh.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2018\/10\/herbst-parasiten-floh.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6594,"url":"https:\/\/www.flora-pharm.de\/blog\/hunderunde-zeit-fuer-entdecker\/","url_meta":{"origin":5558,"position":4},"title":"Hunderunde &#8211; Zeit f\u00fcr Entdecker","author":"Flora Team","date":"24. Juni 2020","format":false,"excerpt":"So wird die t\u00e4gliche Hunderunde zu einem tollen Abenteuer.F\u00fcr die Zufriedenheit Ihres Vierbeiners sind Langeweile und Routine auf der t\u00e4glichen Hunderunde durch das heimatliche Wohngebiet Gift. Nichts Aufregendes, nichts, was die Neugierde anregt, und Herrchen starrt st\u00e4ndig aufs Smartphone \u2013 wie langweilig ist das denn? Dabei l\u00e4sst sich aus dem\u2026","rel":"","context":"In &quot;Haustiere&quot;","block_context":{"text":"Haustiere","link":"https:\/\/www.flora-pharm.de\/blog\/category\/haustiere\/"},"img":{"alt_text":"Hund Entdecker Gassi","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/11\/Hundehaltung-Entdecker.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/11\/Hundehaltung-Entdecker.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/11\/Hundehaltung-Entdecker.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/11\/Hundehaltung-Entdecker.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":8283,"url":"https:\/\/www.flora-pharm.de\/blog\/goldener-tau\/","url_meta":{"origin":5558,"position":5},"title":"Goldener Tau","author":"Flora Team","date":"17. Juni 2022","format":false,"excerpt":"Das Besondere am Waldhonig ist sein Grundstoff. Die Bienen produzieren ihn aus Honigtau, nicht wie \u00fcblich aus Bl\u00fctennektar.","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Waldhonig = Goldener Tau","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2022\/06\/waldhonig-goldener-tau.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2022\/06\/waldhonig-goldener-tau.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2022\/06\/waldhonig-goldener-tau.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2022\/06\/waldhonig-goldener-tau.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/5558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/comments?post=5558"}],"version-history":[{"count":12,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/5558\/revisions"}],"predecessor-version":[{"id":5570,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/5558\/revisions\/5570"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media\/5479"}],"wp:attachment":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media?parent=5558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/categories?post=5558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/tags?post=5558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}