{"id":9303,"date":"2024-11-08T09:44:13","date_gmt":"2024-11-08T08:44:13","guid":{"rendered":"https:\/\/www.flora-pharm.de\/blog\/?p=9303"},"modified":"2024-11-08T09:44:15","modified_gmt":"2024-11-08T08:44:15","slug":"bitter-is-beautiful","status":"publish","type":"post","link":"https:\/\/www.flora-pharm.de\/blog\/bitter-is-beautiful\/","title":{"rendered":"Bitter is beautiful"},"content":{"rendered":"\n<p>Dass Bitterstoffe eine innerlich wohltuende Wirkung haben, wissen wir l\u00e4ngst. Sie finden hier im Blog auch viele <a href=\"https:\/\/www.flora-pharm.de\/blog\/tag\/bitter\/\">Artikel rund um die Bitterstoffe<\/a>. Dass sie aber auch \u00e4u\u00dferlich viel Gutes f\u00fcr uns tun, gilt als neue Erkenntnis. F\u00fcr unsere Haut ist bitter also das neue S\u00fc\u00df.<\/p>\n\n\n\n<p>Zu \u00fcppig gegessen? Darauf gibt\u2019s einen Magenbitter. Bestenfalls in Form von Tee, Urtinktur oder einem Heilpflanzen-Elixier aus Mariendistel, Wermut oder Schafgarbe. Kr\u00e4uter zur Verdauungsf\u00f6rderung gibt\u2019s viele. Gelber Enzian und Tausendg\u00fcldenkraut geh\u00f6ren ebenfalls dazu. Letztere haben es inzwischen auch in die Hautpflege geschafft \u2013 eben dank ihrer Bitterstoffe. Aber was tun sie f\u00fcr unsere sensible H\u00fclle?<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Haut mag es herb<\/h2>\n\n\n\n<p>Lange Zeit ging man davon aus, dass wir Bitterstoffe lediglich schmecken, allenfalls riechen k\u00f6nnen. Als Wissenschaftler der Uniklinik Freiburg vor knapp zehn Jahren auch in der Haut sogenannte Bitter-Rezeptoren fanden, brachten sie einen Stein ins Rollen. Seitdem gibt es in der Naturkosmetik einen neuen Wirkstoff, der offenbar mehr kann, als die Haut nur von au\u00dfen zu pflegen. Amarogentin z\u00e4hlt zu den bittersten Naturstoffen \u00fcberhaupt. Es steckt zum Beispiel im Gelben Enzian und im <a href=\"https:\/\/www.flora-pharm.de\/blog\/tausendgueldenkraut\/\">Tausendg\u00fcldenkraut<\/a>. Rezeptoren reagieren darauf, wie die Forschenden festgestellt haben, und lassen Calcium in alle Zellen der Epidermis, unserer obersten Hautschicht, str\u00f6men. Dadurch kommt der Stoffwechsel der Haut in Schwung. Denn prompt bilden sich Lipide und Proteine, die an der ganz nat\u00fcrlichen R\u00fcckfettung beteiligt sind. Trockene Haut wird somit angeregt, sich selbst zur\u00fcck ins Gleichgewicht zu bringen. F\u00fcr eine ganz bestimmte Patienten-Klientel sind Hautpflege-Produkte mit Bitterstoffen daher sicherlich ein Segen.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Starker Schutzmantel<\/h2>\n\n\n\n<p>Mehr als zwei Millionen Menschen leiden in Deutschland n\u00e4mlich an <a href=\"https:\/\/www.flora-pharm.de\/blog\/neurodermitis-naturheilkundlich-behandeln\/\">Neurodermitis<\/a>. Ebenso viele haben mit Schuppenflechte zu k\u00e4mpfen. Und sogar jedes zehnte Kind hat eine dieser chronischen Hauterkrankungen. Was alle Betroffenen gemeinsam haben: Ihr nat\u00fcrlicher Schutzmantel hat Risse. Cremes und Lotionen mit Bitterstoffen k\u00f6nnen diese gesch\u00e4digte Hautbarriere sozusagen von innen kitten, weil sie die Selbstheilungskr\u00e4fte in Gang setzen und die erforderlichen Wundheilungsprozesse ansto\u00dfen sollen. Wirkstoffen wie Amarogentin wird au\u00dferdem nachgesagt, dass sie unsere Keranozyten stimulieren; das sind Zellen, die kr\u00e4ftigendes Keratin bilden. So bleibt der Feuchtigkeitshaushalt stabil und unser gr\u00f6\u00dftes Organ, die Haut, ist besser vor \u00e4u\u00dferen Einfl\u00fcssen gesch\u00fctzt \u2013 vor Keimen, Feinstaub, trockener Heizungsluft und UV-Strahlen. Auch bei Sonnenbrand und Insektenstichen sollen Bitterstoffe beruhigend wirken, den Juckreiz lindern und die Entz\u00fcndung hemmen. Einst beanspruchte und barrieregesch\u00e4digte Haut, ob durch Ekzeme oder \u00fcbertriebene Hygiene mit zu h\u00e4ufigem und hei\u00dfem Duschen, darf dann wieder strahlen, und zwar von innen heraus.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Bittere \u201eBlumen\u201c<\/h2>\n\n\n\n<p>Der Einsatz von Bitterpflanzen in der Hautpflege ist noch ein recht junger Zweig. Erste Studien der Uniklinik Freiburg zeigen jedoch einen belebenden und entz\u00fcndungshemmenden Effekt bei leichter Neurodermitis. Traditionell werden Gelber Enzian und Tausendg\u00fcldenkraut, also jene Arzneikr\u00e4uter von h\u00f6chstem Bitterwert, bei Magen-Darm-Beschwerden eingesetzt. Bittermittel wirken innerlich nachweislich entkrampfend, kr\u00e4ftigend und ausgleichend \u2013 warum also nicht auch \u00e4u\u00dferlich?! Cremes kommen ohne Nebenwirkungen aus und sind eine tolle Alternative zu cortisonhaltigen Pr\u00e4paraten.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong><em>In Ihrer Apotheke bekommen Sie Hautpflege-Produkte mit Bitterstoffen. Selbstverst\u00e4ndlich haben wir auch f\u00fcr Ihre Fragen ein offenes Ohr und beraten Sie gern sowie individuell abgestimmt. Sprechen Sie uns einfach auf das Thema an.<\/em><\/strong><\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image aligncenter size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"300\" data-attachment-id=\"9293\" data-permalink=\"https:\/\/www.flora-pharm.de\/blog\/naturheilkunde-und-gesundheit-cover-09-2024\/\" data-orig-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/naturheilkunde-und-gesundheit-cover-09-2024.jpg\" data-orig-size=\"450,600\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"naturheilkunde-und-gesundheit-cover-09-2024\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Text mit freundlicher Genehmigung der S &amp;#038; D Verlag GmbH. Das komplette \u201cNaturheilkunde &amp;#038; Gesundheit\u201d Heft bekommen Sie auch bei uns in der Apotheke.&lt;\/p&gt;\n\" data-large-file=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/naturheilkunde-und-gesundheit-cover-09-2024.jpg\" src=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/naturheilkunde-und-gesundheit-cover-09-2024-225x300.jpg\" alt=\"Naturheilkunde &amp; Gesundheit 9-24\" class=\"wp-image-9293\" srcset=\"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/naturheilkunde-und-gesundheit-cover-09-2024-225x300.jpg 225w, https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/naturheilkunde-und-gesundheit-cover-09-2024.jpg 450w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><figcaption class=\"wp-element-caption\">Text mit freundlicher Genehmigung der S &#038; D Verlag GmbH. Das komplette \u201cNaturheilkunde &#038; Gesundheit\u201d Heft bekommen Sie auch bei uns in der Apotheke.<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Bitterstoffe haben innerlich wohltuende Wirkung, klar. Neu ist: auch \u00e4u\u00dferlich tun sie viel Gutes f\u00fcr uns. F\u00fcr unsere Haut ist bitter das neue S\u00fc\u00df.<\/p>\n","protected":false},"author":1,"featured_media":9296,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8],"tags":[416,239,344,422,149,431],"class_list":["post-9303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wissenswert","tag-bitter","tag-ernaehrung","tag-haut","tag-naturheilkunde-und-gesundheit","tag-pflanzenwirkstoffe","tag-phytotherapie","has-post-title","has-post-date","has-post-category","has-post-tag","has-post-comment","has-post-author",""],"jetpack_featured_media_url":"https:\/\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg","jetpack-related-posts":[{"id":7015,"url":"https:\/\/www.flora-pharm.de\/blog\/tausendgueldenkraut\/","url_meta":{"origin":9303,"position":0},"title":"Tausendg\u00fcldenkraut","author":"Flora Team","date":"30. Juni 2020","format":false,"excerpt":"Reich ist, wer gesund ist. Das Tausendg\u00fcldenkraut (Centaurium erythraea, auch: Allerweltsheil, Apothekerblume, Fieberkraut oder Gottesgnadenpflanze) hilft dabei. Das Tausendg\u00fcldenkraut hat viele Namen, die einen ersten Hinweis darauf geben: Hier haben wir es mit einem Universalmittel zu tun. Stefanie Happ erkl\u00e4rt, warum es einfach Gold wert ist. Denn es enth\u00e4lt Substanzen,\u2026","rel":"","context":"In &quot;Heilpflanzen \/ Arzneipflanzen&quot;","block_context":{"text":"Heilpflanzen \/ Arzneipflanzen","link":"https:\/\/www.flora-pharm.de\/blog\/category\/heilpflanzen-arzneipflanzen\/"},"img":{"alt_text":"Tausendg\u00fcldenkraut","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/tausendgueldenkraut.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/tausendgueldenkraut.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/tausendgueldenkraut.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/06\/tausendgueldenkraut.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":12083,"url":"https:\/\/www.flora-pharm.de\/blog\/was-steckt-in-der-pflanze\/","url_meta":{"origin":9303,"position":1},"title":"Was steckt in der Pflanze","author":"Flora Team","date":"12. M\u00e4rz 2026","format":false,"excerpt":"Ob Flavonoide, Bitterstoffe oder \u00e4therische \u00d6le \u2013 Heilpflanzen sind kleine Chemielabore. Ihre nat\u00fcrlichen Wirkstoffe k\u00f6nnen auch uns helfen.","rel":"","context":"In &quot;Heilpflanzen \/ Arzneipflanzen&quot;","block_context":{"text":"Heilpflanzen \/ Arzneipflanzen","link":"https:\/\/www.flora-pharm.de\/blog\/category\/heilpflanzen-arzneipflanzen\/"},"img":{"alt_text":"Ein durchleutetes Blatt zeigt Struktur, der Text beschreibt die Frage: Was steckt in der Pflanze. Erg\u00e4nzend ist noch ein kleines Mikroskop abgebildet, es geht um Pflanzenwirkstoffe","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2026\/01\/was-steckt-in-der-pflanze.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2026\/01\/was-steckt-in-der-pflanze.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2026\/01\/was-steckt-in-der-pflanze.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2026\/01\/was-steckt-in-der-pflanze.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2026\/01\/was-steckt-in-der-pflanze.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":3016,"url":"https:\/\/www.flora-pharm.de\/blog\/bitterstoffe-sind-nuetzlich\/","url_meta":{"origin":9303,"position":2},"title":"Bitterstoffe sind n\u00fctzlich!","author":"Flora Team","date":"8. Dezember 2015","format":false,"excerpt":"Bitteres kurbelt den Stoffwechsel an, st\u00e4rkt die Verdauung und das Immunsystem und sorgt f\u00fcr mehr Wohlbefinden! S\u00fc\u00df Schmeckendes wird von den meisten Menschen geliebt, und nicht nur in der Advents- und Weihnachtszeit. Bittere Lebensmittel essen nur die wenigsten gerne! Es gibt sogar eine angeborene Abneigung gegen\u00fcber Bitterem, die vor dem\u2026","rel":"","context":"In &quot;Heilpflanzen \/ Arzneipflanzen&quot;","block_context":{"text":"Heilpflanzen \/ Arzneipflanzen","link":"https:\/\/www.flora-pharm.de\/blog\/category\/heilpflanzen-arzneipflanzen\/"},"img":{"alt_text":"Mit freundlicher Genehmigung der S & D Verlag GmbH. Das komplette Heft bekommen Sie auch bei uns in der Apotheke.","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2015\/12\/cover-NuG-12-2015-225x300.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6783,"url":"https:\/\/www.flora-pharm.de\/blog\/frischpflanzensaefte-frisch-gepresst\/","url_meta":{"origin":9303,"position":3},"title":"Frischpflanzens\u00e4fte &#8211; Frisch gepresst","author":"Flora Team","date":"3. April 2020","format":false,"excerpt":"Der Saft aus frischen, ganzen Heilpflanzen ist das reinste Elixier, das die Natur zu bieten hat. Schon Aristoteles (384\u2013322 v. Chr.) sagte: \u201eDas Ganze ist mehr als die Summe aller Teile.\u201c Sanfte Naturheilmittel Frischpflanzens\u00e4fte sind sanfte Naturheilmittel. Sie wirken nach einer l\u00e4ngeren Einnahmezeit. Daher nimmt man sie am besten kurm\u00e4\u00dfig\u2026","rel":"","context":"In &quot;Heilpflanzen \/ Arzneipflanzen&quot;","block_context":{"text":"Heilpflanzen \/ Arzneipflanzen","link":"https:\/\/www.flora-pharm.de\/blog\/category\/heilpflanzen-arzneipflanzen\/"},"img":{"alt_text":"Frischpflanzensaft Heilpflanze","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/03\/Frischpflanzensaft.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/03\/Frischpflanzensaft.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/03\/Frischpflanzensaft.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2020\/03\/Frischpflanzensaft.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":11927,"url":"https:\/\/www.flora-pharm.de\/blog\/amara-bitterstoffe\/","url_meta":{"origin":9303,"position":4},"title":"Amara &#8211; Bitterstoffe","author":"Flora Team","date":"18. Dezember 2025","format":false,"excerpt":"Bitteres bringt nicht nur die Verdauung ins Lot. Aber genau diese Wirkung ist in Zeiten schwerer Familienessen gew\u00fcnscht und hilfreich.","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Bitter macht sch\u00f6n, Bitterstoffe sind gut f\u00fcr die Haut","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2024\/08\/bitter-is-beautiful.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":6177,"url":"https:\/\/www.flora-pharm.de\/blog\/gutes-fuer-die-mitte\/","url_meta":{"origin":9303,"position":5},"title":"Gutes f\u00fcr die Mitte","author":"Flora Team","date":"24. Mai 2019","format":false,"excerpt":"Alles, was wir essen und trinken, landet irgendwann im Darm. Warum also nicht Zutaten auf die Reise schicken, die vor Ort f\u00fcr ein gutes Gef\u00fchl sorgen? Bes\u00e4nftigende Kr\u00e4uter, unterst\u00fctzende Gew\u00fcrze: F\u00fcr mehr Wohlbefinden im Bauch empfehlen wir Ihnen diese Spezialisten. Lesen Sie auch Darmgesundheit Unsere Mitte entscheidet \u2013 Frieden im\u2026","rel":"","context":"In &quot;Wissenswert&quot;","block_context":{"text":"Wissenswert","link":"https:\/\/www.flora-pharm.de\/blog\/category\/wissenswert\/"},"img":{"alt_text":"Darmgesundheit","src":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/05\/gutes-fuer-die-mitte.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/05\/gutes-fuer-die-mitte.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/05\/gutes-fuer-die-mitte.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.flora-pharm.de\/blog\/wp-content\/uploads\/2019\/05\/gutes-fuer-die-mitte.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/9303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/comments?post=9303"}],"version-history":[{"count":1,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/9303\/revisions"}],"predecessor-version":[{"id":9304,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/posts\/9303\/revisions\/9304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media\/9296"}],"wp:attachment":[{"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/media?parent=9303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/categories?post=9303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.flora-pharm.de\/blog\/wp-json\/wp\/v2\/tags?post=9303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}